{"id":25,"date":"2025-02-17T01:02:46","date_gmt":"2025-02-17T01:02:46","guid":{"rendered":"https:\/\/becatrading.com\/?page_id=25"},"modified":"2026-05-20T04:37:28","modified_gmt":"2026-05-20T04:37:28","slug":"home","status":"publish","type":"page","link":"https:\/\/becatrading.com\/th\/","title":{"rendered":"Beca Trading Company"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25\" class=\"elementor elementor-25\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27af6af e-flex e-con-boxed e-con e-parent\" data-id=\"27af6af\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2220f7f e-con-full e-flex e-con e-child\" data-id=\"2220f7f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6001bfc8 e-con-full e-flex e-con e-child\" data-id=\"6001bfc8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-61e2e1a2 e-con-full e-flex e-con e-child\" data-id=\"61e2e1a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b8fac0c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3b8fac0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjYxNyIsInRvZ2dsZSI6dHJ1ZX0%3D\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1200pt\" height=\"1200pt\" viewBox=\"0 0 1200 1200\"><path d=\"m200 300h800v100h-800zm0 250h800v100h-800zm0 250h800v100h-800z\" fill-rule=\"evenodd\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-533db1e1 e-con-full e-flex e-con e-child\" data-id=\"533db1e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-806d16f elementor-widget elementor-widget-image\" data-id=\"806d16f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/becatrading.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Asset-1white.svg\" class=\"attachment-large size-large wp-image-1045\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ec2a7ba e-con-full e-flex e-con e-child\" data-id=\"7ec2a7ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c475e4e e-con-full e-flex e-con e-child\" data-id=\"c475e4e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9d5712c e-con-full e-flex e-con e-child\" data-id=\"9d5712c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5b313c elementor-widget elementor-widget-heading\" data-id=\"f5b313c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Weaving Success Across Asia Pacific<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee7ba3c elementor-widget elementor-widget-heading\" data-id=\"ee7ba3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">A Textile Trading Journey<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9dd6e9c e-con-full e-flex e-con e-child\" data-id=\"9dd6e9c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e23d1b e-flex e-con-boxed e-con e-parent\" data-id=\"8e23d1b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5d3d7d4 e-con-full e-flex e-con e-child\" data-id=\"5d3d7d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-538daf5 elementor-widget elementor-widget-text-editor\" data-id=\"538daf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In the bustling heart of Asia\u2019s textile industry, a visionary company began its corporate journey with a mission to redefine textile trading. From its inception, the firm focused on delivering excellence, quickly earning the trust of corporate clients across Asia Pacific. Today, it stands as a regional trusted key player, having served <strong>over 500 projects<\/strong>\u00a0in Hong Kong, China, Thailand, Singapore, Japan, Vietnam,and the Philippines.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d88cdbb e-flex e-con-boxed e-con e-parent\" data-id=\"d88cdbb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eb9a002 e-con-full e-flex e-con e-child\" data-id=\"eb9a002\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ecd8188 e-flex e-con-boxed e-con e-child\" data-id=\"ecd8188\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb537cf elementor-widget elementor-widget-heading\" data-id=\"bb537cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Roots in Expertise, <br \/>Branches Across Borders<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0bf798 elementor-widget elementor-widget-text-editor\" data-id=\"b0bf798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Starting as a corporate-focused boutique agency, the company leveraged its deep industry knowledge to cater to high-demand markets. In <strong>2017<\/strong>, it opens its Thailand office. By <strong>2019<\/strong>, it started\u00a0 serving the Japanese market, renowned for its precision and quality-driven character. Each expansion was strategic, rooted in understanding local nuances while maintaining a global vision.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24a0e80 e-con-full e-flex e-con e-child\" data-id=\"24a0e80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9187b91 elementor-widget elementor-widget-text-editor\" data-id=\"9187b91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"scroll-up\">\n<p style=\"text-align: center;\">HONG KONG<\/p>\n<p style=\"text-align: center;\">THAILAND<\/p>\n<p style=\"text-align: center;\">SINGAPORE<\/p>\n<p style=\"text-align: center;\">JAPAN<\/p>\n<p style=\"text-align: center;\">VIETNAM<\/p>\n<p style=\"text-align: center;\">PHILIPPINES<\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bf4ae4 e-flex e-con-boxed e-con e-parent\" data-id=\"4bf4ae4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-08b15aa e-con-full e-flex e-con e-child\" data-id=\"08b15aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-06b3284 e-con-full e-flex e-con e-child\" data-id=\"06b3284\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6041012 elementor-widget elementor-widget-heading\" data-id=\"6041012\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Milestones that We Are Proud of Reaching<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06eafa1 e-con-full e-flex e-con e-child\" data-id=\"06eafa1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e1c1c0a e-con-full e-flex e-con e-child\" data-id=\"e1c1c0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e60b918 elementor-widget elementor-widget-counter\" data-id=\"e60b918\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">PROJECTS<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"500\" data-from-value=\"300\" data-delimiter=\",\">300<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1d7b04 e-con-full e-flex e-con e-child\" data-id=\"d1d7b04\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-202bf28 elementor-widget elementor-widget-counter\" data-id=\"202bf28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">CLIENTS<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"100\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5bf8497 e-con-full e-flex e-con e-child\" data-id=\"5bf8497\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4622f elementor-widget elementor-widget-counter\" data-id=\"8d4622f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">COUNTRIES<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"10\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fa4a10 e-flex e-con-boxed e-con e-parent\" data-id=\"5fa4a10\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-494a4b1 e-con-full e-flex e-con e-child\" data-id=\"494a4b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-369271e elementor-widget elementor-widget-heading\" data-id=\"369271e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Engine of Innovation: Bespoke Services &amp; A Dynamic Team<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2469b83 elementor-widget elementor-widget-text-editor\" data-id=\"2469b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At its core lies a <strong>strong merchandising team <\/strong>celebrated for agility and creativity.Whether sourcing rare fabrics, optimising supply chains, or crafting tailored solutions, the team offers <strong>bespoke services<\/strong> that adapt to client needs\u2014from luxury hotels to fast-paced retailers. Their expertise spans sustainability, technical textiles, and trend forecasting, ensuring clients stay ahead in competitive markets.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76f9939 e-flex e-con-boxed e-con e-parent\" data-id=\"76f9939\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0b344b6 e-con-full e-flex e-con e-child\" data-id=\"0b344b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3263e21 e-con-full e-flex e-con e-child\" data-id=\"3263e21\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47f03b4 elementor-widget elementor-widget-image\" data-id=\"47f03b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"771\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Cheeva-1024x987.jpg\" class=\"attachment-large size-large wp-image-143\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Cheeva-1024x987.jpg 1024w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Cheeva-300x289.jpg 300w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Cheeva-768x740.jpg 768w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Cheeva-1536x1480.jpg 1536w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Cheeva-2048x1973.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-069f6ca e-flex e-con-boxed e-con e-child\" data-id=\"069f6ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f231fbd elementor-widget elementor-widget-heading\" data-id=\"f231fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A NEW ERA<br \/>\nIntroducing BECA Collections<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccd300d elementor-widget elementor-widget-text-editor\" data-id=\"ccd300d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In 2024, it marked a bold leap forward with the launch of the <strong>BECA Collection<\/strong>, a game-changer for today\u2019s modern design world. Breaking tradition, the collection ditches bulky sample books, embracing innovative swatches presentations. Designers can now flick through fabrics with ease to find its perfect match.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c5aff3 elementor-widget elementor-widget-button\" data-id=\"9c5aff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/becatrading.com\/beca-collection\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BECA Collections<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-357c58a e-flex e-con-boxed e-con e-parent\" data-id=\"357c58a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b8c5e2e e-con-full e-flex e-con e-child\" data-id=\"b8c5e2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9e954a2 e-flex e-con-boxed e-con e-child\" data-id=\"9e954a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4d143e elementor-widget elementor-widget-heading\" data-id=\"d4d143e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ready Stock<br \/>\nRapid Solutions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-801d834 e-flex e-con-boxed e-con e-child\" data-id=\"801d834\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4466d4f elementor-widget elementor-widget-text-editor\" data-id=\"4466d4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Explore over <strong>700 SKUs<\/strong> available stock effortlessly, with materials ranging from natural fibre to high-tech performance fabrics. Warehouses strategically located across Asia, the company guarantees <strong>7 Business Days Dispatch<\/strong>\u00a0to key markets.This \u201cready stock\u201d model eliminates lead-time headaches, empowering designers torespond swiftly to trends and demand spikes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ece4676 e-flex e-con-boxed e-con e-parent\" data-id=\"ece4676\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1c2970b e-con-full e-flex e-con e-child\" data-id=\"1c2970b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b49e368 e-flex e-con-boxed e-con e-child\" data-id=\"b49e368\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bd5406 elementor-widget elementor-widget-heading\" data-id=\"9bd5406\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Future:<br \/> Sustainable Threads<br \/> Global Threads<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b16a993 e-flex e-con-boxed e-con e-child\" data-id=\"b16a993\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-941ffde elementor-widget elementor-widget-text-editor\" data-id=\"941ffde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0As the BECA Collection gains momentum, the company remains committed to innovation and sustainability. Plans are underway to integrate traceability and expand into circular textiles. From its corporate roots to luxury hotels, this story is one of relentless evolution\u2014a tapestry woven with ambition, expertise, and a passion for redefining what\u2019s possible in textiles<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2a8807 e-flex e-con-boxed e-con e-parent\" data-id=\"d2a8807\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dd658ca e-con-full e-flex e-con e-child\" data-id=\"dd658ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fa8924 container-fill-text elementor-widget elementor-widget-heading\" data-id=\"1fa8924\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Join the Fabric of Tomorrow, TODAY.   Join the Fabric of Tomorrow, TODAY.   Join the Fabric of Tomorrow, TODAY.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-366a532 e-flex e-con-boxed e-con e-parent\" data-id=\"366a532\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c32b9cc e-con-full e-flex e-con e-child\" data-id=\"c32b9cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d712b1 elementor-widget elementor-widget-heading\" data-id=\"4d712b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BECA Collection<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f823a00 e-flex e-con-boxed e-con e-parent\" data-id=\"4f823a00\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-732c34e8 e-con-full e-flex e-con e-child\" data-id=\"732c34e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76022928 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"76022928\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/beca-collection\/artificial-leather\/\" target=\"_blank\" tabindex=\"-1\"><img decoding=\"async\" width=\"768\" height=\"531\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/14-768x531.png\" class=\"attachment-medium_large size-medium_large wp-image-1106\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/14-768x531.png 768w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/14-300x207.png 300w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/14-1024x708.png 1024w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/14-1536x1062.png 1536w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/14-2048x1416.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/becatrading.com\/beca-collection\/artificial-leather\/\" target=\"_blank\">Artificial Leather<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-283861b2 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"283861b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/beca-collection\/upholstery-fabric\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Option-5-768x432.png\" class=\"attachment-medium_large size-medium_large wp-image-1102\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Option-5-768x432.png 768w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Option-5-300x169.png 300w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Option-5-1024x576.png 1024w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Option-5-1536x864.png 1536w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Option-5-2048x1151.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/becatrading.com\/beca-collection\/upholstery-fabric\/\" target=\"_blank\">Upholstery Fabric<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-405bfef8 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"405bfef8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/beca-collection\/beca-teflon\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"2560\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Beige-1-scaled.webp\" class=\"attachment-full size-full wp-image-202\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Beige-1-scaled.webp 1440w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Beige-1-169x300.webp 169w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Beige-1-576x1024.webp 576w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Beige-1-768x1365.webp 768w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Beige-1-864x1536.webp 864w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Beige-1-1152x2048.webp 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/becatrading.com\/beca-collection\/beca-teflon\/\" target=\"_blank\">Teflon<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb89152 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"eb89152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/beca-collection\/pe-xerol\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"809\" height=\"815\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/PE-Xorel-Jobref-close-up.jpeg\" class=\"attachment-full size-full wp-image-1129\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/PE-Xorel-Jobref-close-up.jpeg 809w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/PE-Xorel-Jobref-close-up-298x300.jpeg 298w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/PE-Xorel-Jobref-close-up-150x150.jpeg 150w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/PE-Xorel-Jobref-close-up-768x774.jpeg 768w\" sizes=\"(max-width: 809px) 100vw, 809px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/becatrading.com\/beca-collection\/pe-xerol\/\" target=\"_blank\">PE Xorel<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e7b4d7 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2e7b4d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/beca-collection\/outdoor\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"351\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Breeze.jpg\" class=\"attachment-full size-full wp-image-1809\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Breeze.jpg 501w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Breeze-300x210.jpg 300w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Breeze-18x12.jpg 18w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/becatrading.com\/beca-collection\/outdoor\/\" target=\"_blank\">Outdoor<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0194c87 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0194c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/beca-collection\/velvet\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-scaled.webp\" class=\"attachment-full size-full wp-image-1828\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-scaled.webp 2560w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-300x300.webp 300w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-1024x1024.webp 1024w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-150x150.webp 150w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-768x768.webp 768w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-1536x1536.webp 1536w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-2048x2048.webp 2048w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/Velvet-Collection-12x12.webp 12w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/becatrading.com\/beca-collection\/velvet\/\" target=\"_blank\">Velvet<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-784f519 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"784f519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/weaving\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2026\/05\/Collection-Square-Image.jpg\" class=\"attachment-full size-full wp-image-2151\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2026\/05\/Collection-Square-Image.jpg 1000w, https:\/\/becatrading.com\/wp-content\/uploads\/2026\/05\/Collection-Square-Image-300x300.jpg 300w, https:\/\/becatrading.com\/wp-content\/uploads\/2026\/05\/Collection-Square-Image-150x150.jpg 150w, https:\/\/becatrading.com\/wp-content\/uploads\/2026\/05\/Collection-Square-Image-768x768.jpg 768w, https:\/\/becatrading.com\/wp-content\/uploads\/2026\/05\/Collection-Square-Image-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/becatrading.com\/weaving\/\" target=\"_blank\">Weaving<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56f31ca e-flex e-con-boxed e-con e-parent\" data-id=\"56f31ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-31acb47 e-con-full e-flex e-con e-child\" data-id=\"31acb47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba537fb elementor-widget elementor-widget-heading\" data-id=\"ba537fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agency Brands<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68620279 e-flex e-con-boxed e-con e-parent\" data-id=\"68620279\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4833a5b8 e-con-full e-flex e-con e-child\" data-id=\"4833a5b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30a021ee elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"30a021ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/agency-brands\/foglizzo\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"48\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/logo-foglizzo1921.svg\" class=\"attachment-full size-full wp-image-242\" alt=\"\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4851a6e7 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4851a6e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/agency-brands\/futura-leather\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"328\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/FuturaLeathers-640w.png\" class=\"attachment-full size-full wp-image-1177\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/FuturaLeathers-640w.png 600w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/FuturaLeathers-640w-300x164.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6ae02c elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b6ae02c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/becatrading.com\/agency-brands\/stinson\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"640\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/CF-Stinson-Logo.png\" class=\"attachment-full size-full wp-image-1178\" alt=\"\" srcset=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/CF-Stinson-Logo.png 1000w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/CF-Stinson-Logo-300x192.png 300w, https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/CF-Stinson-Logo-768x492.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48125404 e-flex e-con-boxed e-con e-parent\" data-id=\"48125404\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c29a54d e-con-full e-flex e-con e-child\" data-id=\"3c29a54d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-248e1612 elementor-widget elementor-widget-heading\" data-id=\"248e1612\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Our Clients<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13542c29 elementor-widget elementor-widget-image-carousel\" data-id=\"13542c29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;7&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;none&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Aman.svg\" alt=\"Aman\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Baker-McKenzie.svg\" alt=\"Baker &amp; McKenzie\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Cartier-1-300x79.png\" alt=\"Cartier\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Dusit-Thani-Kyoto.svg\" alt=\"Dusit Thani Kyoto\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Dyson_logo.svg-300x114.png\" alt=\"Dyson_logo.svg\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/HKUST.svg\" alt=\"HKUST\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Hong-Kong-Jockey-Club.png\" alt=\"Hong Kong Jockey Club\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/HSBC.svg\" alt=\"HSBC\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/King-Power.svg\" alt=\"King Power\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/MGM-e1740543921643.png\" alt=\"MGM\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/otsuka-logo.png\" alt=\"otsuka-logo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Phillip-Moris.svg\" alt=\"Phillip Moris\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Pullman.svg\" alt=\"Pullman\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/st-regis.svg\" alt=\"st-regis\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Tory-Burch-300x66.png\" alt=\"Tory Burch\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/UBS.svg\" alt=\"UBS\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/cl-logo.png\" alt=\"cl-logo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/chanel-300x63.png\" alt=\"chanel\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/ihg.png\" alt=\"ihg\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/03\/dfs.png\" alt=\"dfs\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/05\/swire-logo-01D062D0CF-seeklogo.com_.png\" alt=\"swire-logo-01D062D0CF-seeklogo.com\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 22\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/04\/unnamed-2.png\" alt=\"unnamed (2)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19cccbd7 e-con-full e-flex e-con e-parent\" data-id=\"19cccbd7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3851f799 e-flex e-con-boxed e-con e-child\" data-id=\"3851f799\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-90f8f84 e-con-full e-flex e-con e-child\" data-id=\"90f8f84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55403331 elementor-widget elementor-widget-heading\" data-id=\"55403331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Stay in touch !<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bcaa60c elementor-widget elementor-widget-text-editor\" data-id=\"7bcaa60c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"forminator-ui forminator-custom-form forminator-custom-form-1327 forminator-design--material  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-1327\" data-uid=\"6a57fec791b05\"><br\/><\/div><form\r\n\t\t\t\tid=\"forminator-module-1327\"\r\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-1327 forminator-design--material  forminator_ajax\"\r\n\t\t\t\tmethod=\"post\"\r\n\t\t\t\tdata-forminator-render=\"0\"\r\n\t\t\t\tdata-form-id=\"1327\"\r\n\t\t\t\t data-color-option=\"theme\" data-design=\"material\" data-grid=\"open\" style=\"display: none;\"\r\n\t\t\t\tdata-uid=\"6a57fec791b05\"\r\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12 \"><div class=\"forminator-field\"><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"Your email address\" id=\"forminator-field-email-1_6a57fec791b05\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><\/div><div class=\"forminator-row\" style=\"margin: 0;\"><div id=\"captcha-1\" class=\"forminator-field-captcha  forminator-col-12 \"><div class=\"forminator-captcha-left forminator-g-recaptcha recaptcha-invisible\" data-theme=\"light\" data-badge=\"bottomright\" data-sitekey=\"6LcHTOsqAAAAAGEPvOr7I1Z8BfXJyAeYOR3iLSc6\" data-size=\"invisible\"><\/div> <\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\"><span>Submit<\/span><span aria-hidden=\"true\"><\/span><\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"5f36a83b8b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/th\/wp-json\/wp\/v2\/pages\/25\" \/><input type=\"hidden\" name=\"form_id\" value=\"1327\"><input type=\"hidden\" name=\"page_id\" value=\"25\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/becatrading.com\/th\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><label for=\"input_2\" class=\"forminator-hidden\" aria-hidden=\"true\">Please do not fill in this field. <input id=\"input_2\" type=\"text\" name=\"input_2\" value=\"\" autocomplete=\"off\"><\/label><\/form><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-211f2794 e-con-full e-flex e-con e-child\" data-id=\"211f2794\" data-element_type=\"container\" data-e-type=\"container\" id=\"contact\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c41dd0 elementor-widget elementor-widget-text-editor\" data-id=\"2c41dd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>ABOUT<br \/><\/strong><a href=\"https:\/\/becatrading.com\/our-work\/\">Our Work<\/a><br \/><a href=\"https:\/\/becatrading.com\/contact\/\">Contact Us<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7551fdce e-con-full e-flex e-con e-child\" data-id=\"7551fdce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5314ebb4 elementor-widget elementor-widget-text-editor\" data-id=\"5314ebb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>BRANDS<\/strong><br \/><a href=\"https:\/\/becatrading.com\/agency-brands\/foglizzo\/\">Foglizzo<\/a><br \/><a href=\"https:\/\/becatrading.com\/agency-brands\/futura-leather\/\">Futura Leathers<\/a><br \/><a href=\"https:\/\/becatrading.com\/agency-brands\/stinson\/\">Stinson<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6034fc4c e-con-full e-flex e-con e-child\" data-id=\"6034fc4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74b02d5d elementor-widget elementor-widget-text-editor\" data-id=\"74b02d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>BECA COLLECTION<br \/><\/strong><a href=\"https:\/\/becatrading.com\/beca-collection\/artificial-leather\/\">Artificial Leather<\/a><br \/><a href=\"https:\/\/becatrading.com\/beca-collection\/upholstery-fabric\/\">Upholstery Fabric<\/a><br \/><a href=\"https:\/\/becatrading.com\/beca-collection\/beca-teflon\/\">Teflon<\/a><br \/><a href=\"https:\/\/becatrading.com\/beca-collection\/pe-xorel\/\">PE Xorel<\/a><br \/><a href=\"https:\/\/becatrading.com\/beca-collection\/outdoor\/\">Outdoor<\/a><br \/><a href=\"https:\/\/becatrading.com\/beca-collection\/velvet\/\">Velvet<\/a><br \/><a href=\"https:\/\/becatrading.com\/weaving\/\">Weaving<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d67298 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"7d67298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>FOLLOW US<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2199a4 elementor-align-end elementor-widget__width-inherit elementor-mobile-align-start elementor-hidden-desktop elementor-hidden-tablet elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d2199a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/becatrading\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Instagram<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/line.me\/ti\/p\/5PSH3_y7ON\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Line<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wa.me\/93115618\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Whatsapp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:contact@becatrading.com\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Email<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-407aa78 elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"407aa78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"trp_language_switcher_shortcode\">\n<div class=\"trp-language-switcher trp-language-switcher-container\" data-no-translation >\n    <div class=\"trp-ls-shortcode-current-language\">\n        <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\" title=\"Thai\" onclick=\"event.preventDefault()\">\n\t\t\t Thai\t\t<\/a>\n    <\/div>\n    <div class=\"trp-ls-shortcode-language\">\n                <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\"  title=\"Thai\" onclick=\"event.preventDefault()\">\n\t\t\t Thai\t\t<\/a>\n                    <a href=\"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/pages\/25#TRPLINKPROCESSED\" title=\"English\">\n             English        <\/a>\n\n        <\/div>\n    <script type=\"application\/javascript\">\n        \/\/ need to have the same with set from JS on both divs. Otherwise it can push stuff around in HTML\n        var trp_ls_shortcodes = document.querySelectorAll('.trp_language_switcher_shortcode .trp-language-switcher');\n        if ( trp_ls_shortcodes.length > 0) {\n            \/\/ get the last language switcher added\n            var trp_el = trp_ls_shortcodes[trp_ls_shortcodes.length - 1];\n\n            var trp_shortcode_language_item = trp_el.querySelector( '.trp-ls-shortcode-language' )\n            \/\/ set width\n            var trp_ls_shortcode_width                                               = trp_shortcode_language_item.offsetWidth + 16;\n            trp_shortcode_language_item.style.width                                  = trp_ls_shortcode_width + 'px';\n            trp_el.querySelector( '.trp-ls-shortcode-current-language' ).style.width = trp_ls_shortcode_width + 'px';\n\n            \/\/ We're putting this on display: none after we have its width.\n            trp_shortcode_language_item.style.display = 'none';\n        }\n    <\/script>\n<\/div>\n<\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53f533fa e-flex e-con-boxed e-con e-parent\" data-id=\"53f533fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65d90a6d e-con-full e-flex e-con e-child\" data-id=\"65d90a6d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d7b1bf elementor-widget elementor-widget-image\" data-id=\"8d7b1bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/becatrading.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"175\" height=\"41\" src=\"https:\/\/becatrading.com\/wp-content\/uploads\/2025\/02\/Asset-1white.svg\" class=\"attachment-full size-full wp-image-1045\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ace0386 e-flex e-con-boxed e-con e-parent\" data-id=\"6ace0386\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c99c38d e-con-full e-flex e-con e-child\" data-id=\"c99c38d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f99a069 elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"f99a069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"trp_language_switcher_shortcode\">\n<div class=\"trp-language-switcher trp-language-switcher-container\" data-no-translation >\n    <div class=\"trp-ls-shortcode-current-language\">\n        <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\" title=\"Thai\" onclick=\"event.preventDefault()\">\n\t\t\t Thai\t\t<\/a>\n    <\/div>\n    <div class=\"trp-ls-shortcode-language\">\n                <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\"  title=\"Thai\" onclick=\"event.preventDefault()\">\n\t\t\t Thai\t\t<\/a>\n                    <a href=\"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/pages\/25#TRPLINKPROCESSED\" title=\"English\">\n             English        <\/a>\n\n        <\/div>\n    <script type=\"application\/javascript\">\n        \/\/ need to have the same with set from JS on both divs. Otherwise it can push stuff around in HTML\n        var trp_ls_shortcodes = document.querySelectorAll('.trp_language_switcher_shortcode .trp-language-switcher');\n        if ( trp_ls_shortcodes.length > 0) {\n            \/\/ get the last language switcher added\n            var trp_el = trp_ls_shortcodes[trp_ls_shortcodes.length - 1];\n\n            var trp_shortcode_language_item = trp_el.querySelector( '.trp-ls-shortcode-language' )\n            \/\/ set width\n            var trp_ls_shortcode_width                                               = trp_shortcode_language_item.offsetWidth + 16;\n            trp_shortcode_language_item.style.width                                  = trp_ls_shortcode_width + 'px';\n            trp_el.querySelector( '.trp-ls-shortcode-current-language' ).style.width = trp_ls_shortcode_width + 'px';\n\n            \/\/ We're putting this on display: none after we have its width.\n            trp_shortcode_language_item.style.display = 'none';\n        }\n    <\/script>\n<\/div>\n<\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abfb5b2 e-con-full e-flex e-con e-child\" data-id=\"abfb5b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-787158e elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"787158e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u00a9 2025 <a href=\"https:\/\/becatrading.com\/\">Beca Trading Company.<\/a> All Rights Reserved.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52d74bb6 e-con-full e-flex e-con e-child\" data-id=\"52d74bb6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41277b02 elementor-icon-list--layout-inline elementor-align-end elementor-mobile-align-center elementor-hidden-mobile elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"41277b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/becatrading\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Instagram<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/line.me\/ti\/p\/5PSH3_y7ON\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Line<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wa.me\/93115618\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Whatsapp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:contact@becatrading.com\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Email<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d300a7 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"7d300a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u00a9 2025 <a href=\"https:\/\/becatrading.com\/\">Beca Trading Company.<\/a><br \/>All Rights Reserved.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Weaving Success Across Asia Pacific A Textile Trading Journey In the bustling heart of Asia\u2019s textile industry, a visionary company began its corporate journey with a mission to redefine textile trading. From its inception, the firm focused on delivering excellence, quickly earning the trust of corporate clients across Asia Pacific. Today, it stands as a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":0,"href":"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"wp:attachment":[{"href":"https:\/\/becatrading.com\/th\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}